{"id":4482,"date":"2021-01-15T15:32:54","date_gmt":"2021-01-15T14:32:54","guid":{"rendered":"https:\/\/ott.wenzel-werbeagentur.de\/worm-gears\/rotors-rotoren\/"},"modified":"2021-02-15T16:56:01","modified_gmt":"2021-02-15T15:56:01","slug":"rotors-rotoren","status":"publish","type":"page","link":"https:\/\/www.zahnrad-ott.de\/en\/worm-gears\/rotors-rotoren\/","title":{"rendered":"Rotors (Rotoren)"},"content":{"rendered":"<p><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-background-position:left top;--awb-border-sizes-top:0px;--awb-border-sizes-bottom:0px;--awb-border-sizes-left:0px;--awb-border-sizes-right:0px;--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:100px;--awb-padding-right:20px;--awb-padding-bottom:100px;--awb-padding-left:20px;--awb-margin-top:0px;--awb-margin-bottom:0px;--awb-background-color:#ffffff;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_2_3 2_3 fusion-two-third fusion-column-first\" style=\"--awb-bg-size:cover;--awb-margin-bottom:0px;width:66.666666666667%;width:calc(66.666666666667% - ( ( 4% ) * 0.66666666666667 ) );margin-right: 4%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><div class=\"fusion-title title fusion-title-1 fusion-sep-none fusion-title-text fusion-title-size-one\" style=\"--awb-text-color:#9e7800;--awb-margin-top-small:0px;--awb-margin-right-small:0px;--awb-margin-bottom-small:20px;--awb-margin-left-small:0px;\"><h1 class=\"fusion-title-heading title-heading-left fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:50;line-height:1.25;\">Rotors<\/h1><\/div><div class=\"fusion-title title fusion-title-2 fusion-sep-none fusion-title-text fusion-title-size-three\" style=\"--awb-text-color:#000000;--awb-margin-top-small:0px;--awb-margin-right-small:0px;--awb-margin-bottom-small:20px;--awb-margin-left-small:0px;\"><h3 class=\"fusion-title-heading title-heading-left fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:25;line-height:1.25;\">Rotary Compressors \/ Rotary-Screw Compressors<\/h3><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:11px;margin-bottom:11px;width:100%;max-width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-text fusion-text-1\"><p style=\"text-align: left;\">We manufacture parts up to 500 mm in diameter and 1,400 mm in profile length.<\/p>\n<p style=\"text-align: left;\">Larger rotors are being manufactured on request.<\/p>\n<p style=\"text-align: left;\">We guarantee highest quality standards with our precise measuring machines.<\/p>\n<\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:11px;margin-bottom:11px;width:100%;max-width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-text fusion-text-2\"><p style=\"text-align: left;\"><strong>Technical Data \/ Specifications:<\/strong><\/p>\n<\/div>\n<div class=\"table-1\">\n<table style=\"border-color: #969696; border-style: solid;\" border=\"1\">\n<tbody>\n<tr>\n<td style=\"width: 350px; height: 50px; text-align: left; vertical-align: middle;\">Outside diameter (\u00d8)<\/td>\n<td style=\"width: 350px; height: 50px; text-align: left; vertical-align: middle;\">up to 500 mm<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 350px; height: 50px; text-align: left; vertical-align: middle;\">Profile length<\/td>\n<td style=\"width: 350px; height: 50px; text-align: left; vertical-align: middle;\">up to 1,400 mm<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 350px; height: 50px; text-align: left; vertical-align: middle;\">Length (workpiece)<\/td>\n<td style=\"width: 350px; height: 50px; text-align: left; vertical-align: middle;\">up to 1,500 mm<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:11px;margin-bottom:11px;width:100%;max-width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-text fusion-text-3\"><p style=\"text-align: left;\">(larger parts on request)<\/p>\n<\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"margin-left: auto;margin-right: auto;margin-top:15px;margin-bottom:15px;width:100%;max-width:100%;\"><\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_3 1_3 fusion-one-third fusion-column-last\" style=\"--awb-bg-size:cover;--awb-margin-bottom:0px;width:33.333333333333%;width:calc(33.333333333333% - ( ( 4% ) * 0.33333333333333 ) );\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><div class=\"fusion-builder-row fusion-builder-row-inner fusion-row\"><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-0 fusion_builder_column_inner_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-padding-top:20px;--awb-padding-right:20px;--awb-padding-bottom:20px;--awb-padding-left:20px;--awb-bg-color:#9e7800;--awb-bg-color-hover:#9e7800;--awb-bg-size:cover;--awb-margin-bottom:0px;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><div class=\"fusion-title title fusion-title-3 fusion-title-text fusion-title-size-five\" style=\"--awb-text-color:#ffffff;--awb-margin-bottom:0px;--awb-margin-top-small:0px;--awb-margin-right-small:0px;--awb-margin-bottom-small:0px;--awb-margin-left-small:0px;\"><h5 class=\"fusion-title-heading title-heading-left fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:20;--minFontSize:20;line-height:1.25;\"><i class=\"fas fa-address-card\"><\/i>\u00a0\u00a0Contact person<\/h5><span class=\"awb-title-spacer\"><\/span><div class=\"title-sep-container\"><div class=\"title-sep sep- sep-solid\" style=\"border-color:#e0dede;\"><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><div class=\"fusion-builder-row fusion-builder-row-inner fusion-row\"><div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-1 fusion_builder_column_inner_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-padding-top:40px;--awb-padding-right:20px;--awb-padding-bottom:20px;--awb-padding-left:20px;--awb-bg-color:#f5f5f5;--awb-bg-color-hover:#f5f5f5;--awb-bg-size:cover;--awb-margin-bottom:0px;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><div class=\"fusion-text fusion-text-4\"><p><strong>Mr. F\u00e4ller<\/strong><br \/>\n<a style=\"color: #000000;\" href=\"tel:00497471705113\">Phone +49 (0) 74 71 \/ 705 \u2010 113<\/a><br \/>\n<a style=\"color: #9e7800;\" href=\"m&#97;&#x69;&#x6c;&#x74;o&#58;&#x6b;&#x2e;&#x66;a&#101;&#x6c;&#x6c;&#x65;r&#64;&#x7a;&#x61;&#x68;n&#114;&#x61;&#x64;&#x2d;o&#116;&#x74;&#x2e;&#x64;e\">&#107;&#x2e;&#102;&#x61;&#101;&#x6c;&#108;&#x65;&#114;&#x40;&#122;&#x61;h&#x6e;r&#x61;d&#x2d;o&#x74;t&#x2e;d&#101;<\/a><\/p>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-2 hundred-percent-fullwidth non-hundred-percent-height-scrolling fusion-no-small-visibility fusion-no-medium-visibility\" style=\"--awb-background-position:left top;--awb-border-sizes-top:0px;--awb-border-sizes-bottom:0px;--awb-border-sizes-left:0px;--awb-border-sizes-right:0px;--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:0px;--awb-padding-right:0px;--awb-padding-bottom:0px;--awb-padding-left:0px;--awb-margin-top:-10px;--awb-margin-bottom:-52px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-2 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;--awb-margin-top:-10px;--awb-margin-bottom:0px;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><div class=\"fusion-column-content-centered\"><div class=\"fusion-column-content\"><div class=\"fusion-image-carousel fusion-image-carousel-auto fusion-image-carousel-1\"><div class=\"awb-carousel awb-swiper awb-swiper-carousel awb-carousel--carousel awb-swiper-dots-position-bottom\" data-layout=\"carousel\" data-autoplay=\"yes\" data-autoplayspeed=\"2500\" data-autoplaypause=\"no\" data-loop=\"yes\" data-columns=\"4\" data-columnsmedium=\"1\" data-columnssmall=\"1\" data-itemmargin=\"4\" data-itemwidth=\"180\" data-touchscroll=\"drag\" data-freemode=\"no\" data-imagesize=\"auto\" data-scrollitems=\"1\" data-centeredslides=\"no\" data-rotationangle=\"50\" data-depth=\"100\" data-speed=\"500\" data-shadow=\"no\" data-pagination=\"bullets\" style=\"--awb-columns:4;--awb-column-spacing:4px;\"><div class=\"swiper-wrapper awb-image-carousel-wrapper fusion-flex-align-items-center\"><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-none\"><img decoding=\"async\" width=\"700\" height=\"500\" src=\"https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-01_zahnrad-ott.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-01_zahnrad-ott-200x143.jpg 200w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-01_zahnrad-ott-400x286.jpg 400w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-01_zahnrad-ott-600x429.jpg 600w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-01_zahnrad-ott.jpg 700w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 915px) 290px, (min-width: 824px) 386px, (min-width: 732px) 579px, (min-width: 640px) 732px, \" \/><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-none\"><img decoding=\"async\" width=\"700\" height=\"500\" src=\"https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-02_zahnrad-ott.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-02_zahnrad-ott-200x143.jpg 200w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-02_zahnrad-ott-400x286.jpg 400w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-02_zahnrad-ott-600x429.jpg 600w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-02_zahnrad-ott.jpg 700w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 915px) 290px, (min-width: 824px) 386px, (min-width: 732px) 579px, (min-width: 640px) 732px, \" \/><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-none\"><img decoding=\"async\" width=\"700\" height=\"500\" src=\"https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-03_zahnrad-ott.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-03_zahnrad-ott-200x143.jpg 200w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-03_zahnrad-ott-400x286.jpg 400w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-03_zahnrad-ott-600x429.jpg 600w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-03_zahnrad-ott.jpg 700w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 915px) 290px, (min-width: 824px) 386px, (min-width: 732px) 579px, (min-width: 640px) 732px, \" \/><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-none\"><img decoding=\"async\" width=\"700\" height=\"500\" src=\"https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-04_zahnrad-ott.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-04_zahnrad-ott-200x143.jpg 200w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-04_zahnrad-ott-400x286.jpg 400w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-04_zahnrad-ott-600x429.jpg 600w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-04_zahnrad-ott.jpg 700w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 915px) 290px, (min-width: 824px) 386px, (min-width: 732px) 579px, (min-width: 640px) 732px, \" \/><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-none\"><img decoding=\"async\" width=\"700\" height=\"500\" src=\"https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-05_zahnrad-ott.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-05_zahnrad-ott-200x143.jpg 200w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-05_zahnrad-ott-400x286.jpg 400w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-05_zahnrad-ott-600x429.jpg 600w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-05_zahnrad-ott.jpg 700w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 915px) 290px, (min-width: 824px) 386px, (min-width: 732px) 579px, (min-width: 640px) 732px, \" \/><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-none\"><img decoding=\"async\" width=\"700\" height=\"500\" src=\"https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-06_zahnrad-ott.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-06_zahnrad-ott-200x143.jpg 200w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-06_zahnrad-ott-400x286.jpg 400w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-06_zahnrad-ott-600x429.jpg 600w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-06_zahnrad-ott.jpg 700w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 915px) 290px, (min-width: 824px) 386px, (min-width: 732px) 579px, (min-width: 640px) 732px, \" \/><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-none\"><img decoding=\"async\" width=\"700\" height=\"500\" src=\"https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-07_zahnrad-ott.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-07_zahnrad-ott-200x143.jpg 200w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-07_zahnrad-ott-400x286.jpg 400w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-07_zahnrad-ott-600x429.jpg 600w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-07_zahnrad-ott.jpg 700w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 915px) 290px, (min-width: 824px) 386px, (min-width: 732px) 579px, (min-width: 640px) 732px, \" \/><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-none\"><img decoding=\"async\" width=\"700\" height=\"500\" src=\"https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-08_zahnrad-ott.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-08_zahnrad-ott-200x143.jpg 200w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-08_zahnrad-ott-400x286.jpg 400w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-08_zahnrad-ott-600x429.jpg 600w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-08_zahnrad-ott.jpg 700w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 915px) 290px, (min-width: 824px) 386px, (min-width: 732px) 579px, (min-width: 640px) 732px, \" \/><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-none\"><img decoding=\"async\" width=\"700\" height=\"500\" src=\"https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-09_zahnrad-ott.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-09_zahnrad-ott-200x143.jpg 200w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-09_zahnrad-ott-400x286.jpg 400w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-09_zahnrad-ott-600x429.jpg 600w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-09_zahnrad-ott.jpg 700w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 915px) 290px, (min-width: 824px) 386px, (min-width: 732px) 579px, (min-width: 640px) 732px, \" \/><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-none\"><img decoding=\"async\" width=\"700\" height=\"500\" src=\"https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-10_zahnrad-ott.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-10_zahnrad-ott-200x143.jpg 200w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-10_zahnrad-ott-400x286.jpg 400w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-10_zahnrad-ott-600x429.jpg 600w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-10_zahnrad-ott.jpg 700w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 915px) 290px, (min-width: 824px) 386px, (min-width: 732px) 579px, (min-width: 640px) 732px, \" \/><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-none\"><img decoding=\"async\" width=\"700\" height=\"500\" src=\"https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-11_zahnrad-ott.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-11_zahnrad-ott-200x143.jpg 200w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-11_zahnrad-ott-400x286.jpg 400w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-11_zahnrad-ott-600x429.jpg 600w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-11_zahnrad-ott.jpg 700w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 915px) 290px, (min-width: 824px) 386px, (min-width: 732px) 579px, (min-width: 640px) 732px, \" \/><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-none\"><img decoding=\"async\" width=\"700\" height=\"500\" src=\"https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-12_zahnrad-ott.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-12_zahnrad-ott-200x143.jpg 200w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-12_zahnrad-ott-400x286.jpg 400w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-12_zahnrad-ott-600x429.jpg 600w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-12_zahnrad-ott.jpg 700w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 915px) 290px, (min-width: 824px) 386px, (min-width: 732px) 579px, (min-width: 640px) 732px, \" \/><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-none\"><img decoding=\"async\" width=\"700\" height=\"500\" src=\"https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-13_zahnrad-ott.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-13_zahnrad-ott-200x143.jpg 200w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-13_zahnrad-ott-400x286.jpg 400w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-13_zahnrad-ott-600x429.jpg 600w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-13_zahnrad-ott.jpg 700w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 915px) 290px, (min-width: 824px) 386px, (min-width: 732px) 579px, (min-width: 640px) 732px, \" \/><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-none\"><img decoding=\"async\" width=\"700\" height=\"500\" src=\"https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-14_zahnrad-ott.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-14_zahnrad-ott-200x143.jpg 200w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-14_zahnrad-ott-400x286.jpg 400w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-14_zahnrad-ott-600x429.jpg 600w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-14_zahnrad-ott.jpg 700w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 915px) 290px, (min-width: 824px) 386px, (min-width: 732px) 579px, (min-width: 640px) 732px, \" \/><\/div><\/div><\/div><\/div><div class=\"awb-swiper-button awb-swiper-button-prev\"><i class=\"awb-icon-angle-left\" aria-hidden=\"true\"><\/i><\/div><div class=\"awb-swiper-button awb-swiper-button-next\"><i class=\"awb-icon-angle-right\" aria-hidden=\"true\"><\/i><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-3 hundred-percent-fullwidth non-hundred-percent-height-scrolling fusion-no-large-visibility\" style=\"--awb-background-position:left top;--awb-border-sizes-top:0px;--awb-border-sizes-bottom:0px;--awb-border-sizes-left:0px;--awb-border-sizes-right:0px;--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:0px;--awb-padding-right:0px;--awb-padding-bottom:0px;--awb-padding-left:0px;--awb-margin-top:-10px;--awb-margin-bottom:-52px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-3 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"--awb-bg-size:cover;--awb-margin-top:-10px;--awb-margin-bottom:0px;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><div class=\"fusion-column-content-centered\"><div class=\"fusion-column-content\"><div class=\"fusion-image-carousel fusion-image-carousel-auto fusion-image-carousel-2\"><div class=\"awb-carousel awb-swiper awb-swiper-carousel awb-carousel--carousel awb-swiper-dots-position-bottom\" data-layout=\"carousel\" data-autoplay=\"yes\" data-autoplayspeed=\"2500\" data-autoplaypause=\"no\" data-loop=\"yes\" data-columns=\"1\" data-columnsmedium=\"1\" data-columnssmall=\"1\" data-itemmargin=\"0\" data-itemwidth=\"180\" data-touchscroll=\"drag\" data-freemode=\"no\" data-imagesize=\"auto\" data-scrollitems=\"1\" data-centeredslides=\"no\" data-rotationangle=\"50\" data-depth=\"100\" data-speed=\"500\" data-shadow=\"no\" data-pagination=\"bullets\" style=\"--awb-columns:1;--awb-column-spacing:0px;\"><div class=\"swiper-wrapper awb-image-carousel-wrapper fusion-flex-align-items-center\"><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-none\"><img decoding=\"async\" width=\"700\" height=\"500\" src=\"https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-01_zahnrad-ott.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-01_zahnrad-ott-200x143.jpg 200w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-01_zahnrad-ott-300x214.jpg 300w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-01_zahnrad-ott-400x286.jpg 400w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-01_zahnrad-ott-600x429.jpg 600w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-01_zahnrad-ott.jpg 700w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-none\"><img decoding=\"async\" width=\"700\" height=\"500\" src=\"https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-02_zahnrad-ott.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-02_zahnrad-ott-200x143.jpg 200w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-02_zahnrad-ott-300x214.jpg 300w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-02_zahnrad-ott-400x286.jpg 400w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-02_zahnrad-ott-600x429.jpg 600w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-02_zahnrad-ott.jpg 700w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-none\"><img decoding=\"async\" width=\"700\" height=\"500\" src=\"https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-03_zahnrad-ott.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-03_zahnrad-ott-200x143.jpg 200w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-03_zahnrad-ott-300x214.jpg 300w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-03_zahnrad-ott-400x286.jpg 400w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-03_zahnrad-ott-600x429.jpg 600w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-03_zahnrad-ott.jpg 700w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-none\"><img decoding=\"async\" width=\"700\" height=\"500\" src=\"https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-04_zahnrad-ott.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-04_zahnrad-ott-200x143.jpg 200w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-04_zahnrad-ott-300x214.jpg 300w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-04_zahnrad-ott-400x286.jpg 400w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-04_zahnrad-ott-600x429.jpg 600w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-04_zahnrad-ott.jpg 700w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-none\"><img decoding=\"async\" width=\"700\" height=\"500\" src=\"https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-05_zahnrad-ott.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-05_zahnrad-ott-200x143.jpg 200w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-05_zahnrad-ott-300x214.jpg 300w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-05_zahnrad-ott-400x286.jpg 400w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-05_zahnrad-ott-600x429.jpg 600w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-05_zahnrad-ott.jpg 700w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-none\"><img decoding=\"async\" width=\"700\" height=\"500\" src=\"https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-06_zahnrad-ott.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-06_zahnrad-ott-200x143.jpg 200w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-06_zahnrad-ott-300x214.jpg 300w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-06_zahnrad-ott-400x286.jpg 400w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-06_zahnrad-ott-600x429.jpg 600w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-06_zahnrad-ott.jpg 700w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-none\"><img decoding=\"async\" width=\"700\" height=\"500\" src=\"https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-07_zahnrad-ott.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-07_zahnrad-ott-200x143.jpg 200w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-07_zahnrad-ott-300x214.jpg 300w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-07_zahnrad-ott-400x286.jpg 400w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-07_zahnrad-ott-600x429.jpg 600w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-07_zahnrad-ott.jpg 700w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-none\"><img decoding=\"async\" width=\"700\" height=\"500\" src=\"https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-08_zahnrad-ott.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-08_zahnrad-ott-200x143.jpg 200w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-08_zahnrad-ott-300x214.jpg 300w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-08_zahnrad-ott-400x286.jpg 400w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-08_zahnrad-ott-600x429.jpg 600w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-08_zahnrad-ott.jpg 700w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-none\"><img decoding=\"async\" width=\"700\" height=\"500\" src=\"https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-09_zahnrad-ott.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-09_zahnrad-ott-200x143.jpg 200w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-09_zahnrad-ott-300x214.jpg 300w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-09_zahnrad-ott-400x286.jpg 400w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-09_zahnrad-ott-600x429.jpg 600w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-09_zahnrad-ott.jpg 700w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-none\"><img decoding=\"async\" width=\"700\" height=\"500\" src=\"https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-10_zahnrad-ott.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-10_zahnrad-ott-200x143.jpg 200w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-10_zahnrad-ott-300x214.jpg 300w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-10_zahnrad-ott-400x286.jpg 400w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-10_zahnrad-ott-600x429.jpg 600w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-10_zahnrad-ott.jpg 700w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-none\"><img decoding=\"async\" width=\"700\" height=\"500\" src=\"https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-11_zahnrad-ott.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-11_zahnrad-ott-200x143.jpg 200w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-11_zahnrad-ott-300x214.jpg 300w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-11_zahnrad-ott-400x286.jpg 400w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-11_zahnrad-ott-600x429.jpg 600w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-11_zahnrad-ott.jpg 700w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-none\"><img decoding=\"async\" width=\"700\" height=\"500\" src=\"https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-12_zahnrad-ott.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-12_zahnrad-ott-200x143.jpg 200w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-12_zahnrad-ott-300x214.jpg 300w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-12_zahnrad-ott-400x286.jpg 400w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-12_zahnrad-ott-600x429.jpg 600w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-12_zahnrad-ott.jpg 700w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-none\"><img decoding=\"async\" width=\"700\" height=\"500\" src=\"https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-13_zahnrad-ott.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-13_zahnrad-ott-200x143.jpg 200w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-13_zahnrad-ott-300x214.jpg 300w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-13_zahnrad-ott-400x286.jpg 400w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-13_zahnrad-ott-600x429.jpg 600w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-13_zahnrad-ott.jpg 700w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-none\"><img decoding=\"async\" width=\"700\" height=\"500\" src=\"https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-14_zahnrad-ott.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-14_zahnrad-ott-200x143.jpg 200w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-14_zahnrad-ott-300x214.jpg 300w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-14_zahnrad-ott-400x286.jpg 400w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-14_zahnrad-ott-600x429.jpg 600w, https:\/\/www.zahnrad-ott.de\/wp-content\/uploads\/2020\/12\/carousel_rotoren-14_zahnrad-ott.jpg 700w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/div><\/div><\/div><\/div><div class=\"awb-swiper-button awb-swiper-button-prev\"><i class=\"awb-icon-angle-left\" aria-hidden=\"true\"><\/i><\/div><div class=\"awb-swiper-button awb-swiper-button-next\"><i class=\"awb-icon-angle-right\" aria-hidden=\"true\"><\/i><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-4 hundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-background-position:left top;--awb-border-sizes-top:0px;--awb-border-sizes-bottom:0px;--awb-border-sizes-left:0px;--awb-border-sizes-right:0px;--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:50px;--awb-padding-right:20px;--awb-padding-bottom:30px;--awb-padding-left:20px;--awb-margin-top:0px;--awb-margin-bottom:0px;--awb-background-color:#9e7800;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-4 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last fusion-column-inner-bg-wrapper\" style=\"--awb-inner-bg-size:cover;--awb-margin-bottom:0px;\"><span class=\"fusion-column-inner-bg hover-type-none\"><a class=\"fusion-column-anchor\" href=\"https:\/\/www.zahnrad-ott.de\/en\/contact\/\"><span class=\"fusion-column-inner-bg-image\"><\/span><\/a><\/span><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-column-wrapper-legacy\"><div class=\"fusion-column-content-centered\"><div class=\"fusion-column-content\"><div class=\"fusion-title title fusion-title-4 fusion-sep-none fusion-title-center fusion-title-text fusion-title-size-two\" style=\"--awb-text-color:#ffffff;--awb-margin-top-small:0px;--awb-margin-right-small:0px;--awb-margin-bottom-small:20px;--awb-margin-left-small:0px;\"><h2 class=\"fusion-title-heading title-heading-center fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:25;line-height:1.25;\">You need technical advice?<\/h2><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":3252,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"100-width.php","meta":{"footnotes":""},"class_list":["post-4482","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.zahnrad-ott.de\/en\/wp-json\/wp\/v2\/pages\/4482","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zahnrad-ott.de\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.zahnrad-ott.de\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.zahnrad-ott.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zahnrad-ott.de\/en\/wp-json\/wp\/v2\/comments?post=4482"}],"version-history":[{"count":8,"href":"https:\/\/www.zahnrad-ott.de\/en\/wp-json\/wp\/v2\/pages\/4482\/revisions"}],"predecessor-version":[{"id":4838,"href":"https:\/\/www.zahnrad-ott.de\/en\/wp-json\/wp\/v2\/pages\/4482\/revisions\/4838"}],"up":[{"embeddable":true,"href":"https:\/\/www.zahnrad-ott.de\/en\/wp-json\/wp\/v2\/pages\/3252"}],"wp:attachment":[{"href":"https:\/\/www.zahnrad-ott.de\/en\/wp-json\/wp\/v2\/media?parent=4482"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}